{"id":18467,"date":"2020-08-06T14:26:49","date_gmt":"2020-08-06T11:26:49","guid":{"rendered":"https:\/\/web-dev.iptp.net\/?page_id=18467"},"modified":"2026-04-21T07:08:27","modified_gmt":"2026-04-21T04:08:27","slug":"remote-office","status":"publish","type":"page","link":"https:\/\/iptp.org\/zh_CN\/office-solutions\/remote-office\/","title":{"rendered":"\u8fdc\u7a0b\u529e\u516c"},"content":{"rendered":"<div class=\"section section-page section-dcloud-hero\" style=\"--pcloud-banner:url('\/wp-content\/uploads\/emote-office-banner-1.png')\">\n<div class=\"inner --have-img\">\n<div class=\"text-block text-start\">\n<h1><span style=\"color:#F08F1E;display:block;\">&#36828;&#31243;&#21150;&#20844;&#23460;<\/span><\/h1>\n<p class=\"text-start mb-0\">IPTP Networks &#20026;&#24744;&#25552;&#20379;&#19968;&#20010;&#23436;&#25972;&#30340;&#24037;&#20316;<br>&#29615;&#22659;&#65292;&#23601;&#20687;&#24744;&#21150;&#20844;&#23460;&#37324;&#30340;&#19968;&#21488;&#26222;&#36890;&#26426;&#22120;&#19968;&#26679;<\/p>\n<\/div>\n<div class=\"--is-desktop\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"&#36828;&#31243;&#21150;&#20844;&#23460;\" data-src=\"\/wp-content\/uploads\/remote-office-icon-1.png\" class=\"lazy\"><\/div>\n<\/div>\n<div class=\"--is-mobile\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" atl=\"&#36828;&#31243;&#21150;&#20844;&#23460;\" data-src=\"\/wp-content\/uploads\/remote-office-icon-1.png\" class=\"lazy\"><\/div>\n<\/div><div class=\"section\"><div class=\"inner innerbreadcrum\"><div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\tHome\n<\/span><\/div><\/div><\/div><div class=\"inner\">\n&#22914;&#20309;&#32452;&#32455;&#19968;&#20010;&#22312;&#20219;&#20309;&#24773;&#20917;&#19979;&#37117;&#33021;&#32500;&#25345;&#30340;&#19994;&#21153;&#27969;&#31243;&#21644;&#19987;&#19994;&#65311; &#28789;&#27963;&#24615;&#26159;&#29616;&#20195;&#19994;&#21153;&#22242;&#38431;&#30340;&#24517;&#22791;&#26465;&#20214;&#12290;\n<p>IPTP Networks &#20026;&#24744;&#25552;&#20379;&#19968;&#20010;&#23436;&#25972;&#30340;&#24037;&#20316;&#29615;&#22659;&#65292;&#23601;&#20687;&#24744;&#21150;&#20844;&#23460;&#30340;&#26222;&#36890;&#26426;&#22120;&#19968;&#26679;&#12290; &#29992;&#25143;&#24037;&#20316;&#31354;&#38388;&#20301;&#20110;&#22320;&#29702;&#20998;&#24067;&#24335;&#20113;&#26381;&#21153;&#22120;&#20013;&#65292;&#21253;&#25324;&#20351;&#29992;&#30340;&#25991;&#26723;&#12289;&#37038;&#20214;&#31243;&#24207;&#12289;&#21150;&#20844;&#24212;&#29992;&#31243;&#24207;&#21644;&#32593;&#32476;&#36164;&#28304;&#12290;<\/p>\n<p>&#21487;&#20197;&#20174;&#20219;&#20309;&#26377;&#20114;&#32852;&#32593;&#30340;&#22320;&#26041;&#35775;&#38382;&#24037;&#20316;&#21306;&#65292;&#26080;&#35770;&#26159;&#32593;&#21543;&#12289;&#31227;&#21160;&#35774;&#22791;&#36824;&#26159;&#25151;&#23376;&#12290; &#21452;&#37325;&#36523;&#20221;&#39564;&#35777;&#30340;&#21019;&#26032;&#25216;&#26415;&#25490;&#38500;&#20102;&#38543;&#26426;&#35775;&#38382;&#35813;&#31354;&#38388;&#30340;&#20219;&#20309;&#21487;&#33021;&#24615;&#12290;<\/p>\n<hr>\n<p><strong>&#36828;&#31243;&#21150;&#20844;&#23460;&#21253;&#25324;: <\/strong><\/p>\n<h2>&#36828;&#31243;&#26700;&#38754;<\/h2>\n<p>&#36828;&#31243;&#26700;&#38754;&#21487;&#24110;&#21161;&#24744;&#30340;&#20844;&#21496;&#37096;&#32626;&#25176;&#31649;&#22312;&#19987;&#29992;&#23433;&#20840;&#22522;&#30784;&#35774;&#26045;&#20013;&#30340;&#29615;&#22659;&#65292;&#24744;&#22312;&#21487;&#20197;&#20219;&#20309;&#35774;&#22791;&#19978;&#20351;&#29992;&#23427;&#12290;<br>\n&#35813;&#26381;&#21153;&#34987;&#35748;&#20026;&#26159;&#19968;&#31181;&#26041;&#20415;&#19988;&#26377;&#21560;&#24341;&#21147;&#30340;&#35299;&#20915;&#26041;&#26696;&#65292;&#36866;&#29992;&#20110;&#24076;&#26395;&#33719;&#24471;&#26368;&#39640;&#32423;&#21035;&#30340;&#23433;&#20840;&#24615;&#21644;&#31616;&#21333;&#24615;&#32780;&#26080;&#38656;&#36141;&#20080; IT &#32500;&#25252;&#36719;&#20214;&#30340;&#29992;&#25143;&#12290; &#36828;&#31243;&#26700;&#38754;&#30340;&#22909;&#22788;&#21253;&#25324;&#26356;&#36731;&#26494;&#30340;&#34917;&#19969;&#31649;&#29702;&#21644;&#36719;&#20214;&#26356;&#26032;&#12289;&#26356;&#24555;&#30340;&#36801;&#31227;&#12289;&#26356;&#24555;&#30340;&#26032;&#29992;&#25143;&#37197;&#32622;&#12289;&#26356;&#22909;&#30340;&#28798;&#38590;&#35268;&#21010;&#21644;&#24674;&#22797;&#20197;&#21450;&#25913;&#36827;&#30340;&#24212;&#29992;&#31243;&#24207;&#21644;&#25968;&#25454;&#23433;&#20840;&#24615;&#12290;<\/p>\n<hr>\n<h2>IPSec VPN<\/h2>\n<p>&#25105;&#20204;&#30340;&#19987;&#29992; VPN &#35299;&#20915;&#26041;&#26696;&#20860;&#20855;&#23433;&#20840;&#24615;&#21644;&#28789;&#27963;&#24615;&#12290; &#20026;&#30830;&#20445;&#36816;&#33829;&#39034;&#21033;&#36827;&#34892;&#65292;&#27599;&#20010;&#20225;&#19994;&#37117;&#38656;&#35201;&#23433;&#20840;&#30340;&#31449;&#28857;&#21040;&#31449;&#28857;&#36830;&#25509;&#12290; &#25105;&#20204;&#20026;&#24744;&#25552;&#20379;&#20855;&#26377; DES&#12289;3DES &#21644; AES &#21152;&#23494;&#30340;&#26381;&#21153;&#65292;&#24182;&#21487;&#19982;&#21463;&#31649;&#38450;&#28779;&#22681;&#19968;&#36215;&#25552;&#20379;&#12290;&#25105;&#20204;&#30340;&#24320;&#25918;&#26631;&#20934;&#26694;&#26550;&#65288;&#22522;&#20110; RFC &#35268;&#33539;&#21644; IPsec &#21327;&#35758;&#65289;&#25552;&#20379; IPsec &#21152;&#23494;&#65292;&#24182;&#36890;&#36807;&#26410;&#21463;&#20445;&#25252;&#30340;&#32593;&#32476;&#65288;&#20363;&#22914;&#20114;&#32852;&#32593;&#65289;&#25552;&#20379;&#38567;&#36947;&#21327;&#35758;&#12289;&#25968;&#25454;&#26426;&#23494;&#24615;&#12289;&#25968;&#25454;&#23436;&#25972;&#24615;&#21644;&#25968;&#25454;&#36523;&#20221;&#39564;&#35777;&#65292;&#25152;&#26377;&#36825;&#20123;&#37117;&#36890;&#36807;&#31169;&#26377;&#32593;&#32476;&#19978;&#30340;&#21152;&#23494;&#25968;&#25454;&#27969; &#25110;&#20844;&#20849;&#32593;&#32476;&#12290;<\/p>\n<hr>\n<h2>IP&#30005;&#35805;<\/h2>\n<p>&#36890;&#36807;&#20114;&#32852;&#32593;&#36890;&#35805;&#65288;&#19982;&#20256;&#32479;&#30005;&#35805;&#31995;&#32479;&#30456;&#27604;&#65289;&#21487;&#24110;&#21161;&#20225;&#19994;&#20027;&#21033;&#29992;&#20114;&#32852;&#32593;&#36830;&#25509;&#20197;&#21450;&#38543;&#38468;&#30340;&#30828;&#20214;&#21644;&#24212;&#29992;&#31243;&#24207;&#26356;&#26377;&#25928;&#22320;&#36827;&#34892;&#36890;&#20449;&#12290;&#19982;&#20256;&#32479;&#30005;&#35805;&#31995;&#32479;&#30456;&#27604;&#65292;IP &#30005;&#35805;&#30340;&#20248;&#21183;&#38750;&#24120;&#26126;&#26174;&#12290;&#23427;&#26377;&#21161;&#20110;&#20943;&#23569;&#30005;&#20449;&#26381;&#21153;&#30340;&#27599;&#26376;&#36134;&#21333;&#65292;&#25552;&#39640;&#36890;&#20449;&#31995;&#32479;&#30340;&#25928;&#29575;&#65292;&#28155;&#21152;&#35768;&#22810;&#21019;&#26032;&#30340;&#34701;&#21512;&#21151;&#33021;&#65292;&#24182;&#20462;&#25913;&#24744;&#30340;&#21150;&#20844;&#23460;&#22806;&#35266;&#65292;&#20351;&#20854;&#31526;&#21512;&#24403;&#20195;&#23457;&#32654;&#26631;&#20934;&#12290;<\/p>\n<p>&#36828;&#31243;&#21150;&#20844;&#21487;&#20197;&#22312;&#20219;&#20309;&#26234;&#33021;&#35774;&#22791;&#19978;&#36816;&#34892;&mdash;&mdash;&#25163;&#26426;&#65288;iOS &#21644; Android&#65289;&#12289;&#20219;&#20309;&#31227;&#21160;&#24179;&#26495;&#30005;&#33041;&#12289;&#19978;&#32593;&#26412;&#65292;&#24403;&#28982;&#36824;&#26377;&#26222;&#36890;&#30340;&#26700;&#19978;&#22411;&#30005;&#33041;&#12290;&#20219;&#20309;&#29616;&#20195; Microsoft Windows&trade; &#21644; Linux &#25805;&#20316;&#31995;&#32479;&#37117;&#21487;&#20197;&#29992;&#20316;&#36828;&#31243;&#24037;&#20316;&#29615;&#22659;&#12290;&#27599;&#21608; 7 &#22825;&#12289;&#27599;&#22825; 24 &#23567;&#26102;&#37117;&#21487;&#20197;&#20174;&#20219;&#20309;&#21487;&#20197;&#35775;&#38382;&#20114;&#32852;&#32593;&#30340;&#22320;&#26041;&#35775;&#38382;&#24744;&#30340;&#36828;&#31243;&#31995;&#32479;&#12290;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"lazy alignleft size-full wp-image-17308\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" alt=\"\" width=\"1017\" height=\"380\" data-src=\"\/wp-content\/uploads\/remote-office01.png\" srcset=\"https:\/\/iptp.org\/wp-content\/uploads\/remote-office01.png 1017w, https:\/\/iptp.org\/wp-content\/uploads\/remote-office01-300x112.png 300w, https:\/\/iptp.org\/wp-content\/uploads\/remote-office01-768x287.png 768w\" sizes=\"(max-width: 1017px) 100vw, 1017px\"><\/p><noscript><img decoding=\"async\" loading=\"lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"\" width=\"1017\" height=\"380\" class=\"alignleft size-full wp-image-17308 lazy\" srcset=\"https:\/\/iptp.org\/wp-content\/uploads\/remote-office01.png 1017w, https:\/\/iptp.org\/wp-content\/uploads\/remote-office01-300x112.png 300w, https:\/\/iptp.org\/wp-content\/uploads\/remote-office01-768x287.png 768w\" sizes=\"(max-width: 1017px) 100vw, 1017px\" data-src=\"\/wp-content\/uploads\/remote-office01.png\"><\/noscript>\n<h2>&#36828;&#31243;&#21150;&#20844;&#30340;&#22909;&#22788;:<\/h2>\n<ul>\n<li>&#24615;&#20215;&#27604;&#39640;<\/li>\n<li>&#22797;&#21512;&#24335;&#30340;<\/li>\n<li>&#26080;&#38556;&#30861;<\/li>\n<li>&#23433;&#20840;<\/li>\n<\/ul>\n<p>IPTP Networks &#24456;&#20048;&#24847;&#38543;&#26102;&#38543;&#22320;&#20026;&#24744;&#25552;&#20379;&#22797;&#21512;&#24335;&#30340;&#36828;&#31243;&#21150;&#20844;&#35299;&#20915;&#26041;&#26696;&#12290; &#35831;&#38543;&#26102;&#32852;&#31995;&#25105;&#20204;&#30340;&#38144;&#21806;&#22242;&#38431;<a><span class=\"sp-user\">sales<\/span><span class=\"sp-domain\">iptp.net<\/span><\/a>&#20197;&#33719;&#21462;&#26377;&#20851;&#27492;&#26381;&#21153;&#30340;&#26356;&#22810;&#35814;&#32454;&#20449;&#24687;&#12290;<\/p>\n\t\r\n\r\n\t\r\n\t<div>\r\n\t\t<button type=\"button\" class=\"btn btn-primary btn__jumboix btn-lg js-target-div mt-2 js-fixed-button-open-request-form \" data-target=\"jumboIX__modal\">\r\n\t\t\t&#35831;&#27714;&#25253;&#20215;\t\t<\/button>\r\n\t<\/div>\r\n\t\r\n\t<script type=\"text\/javascript\">\r\n\t\tjQuery(function($){\r\n\r\n\t\t\t $(document).on('click', '#jumboIX__modal.active', function(e){\r\n\t\t        e.preventDefault();\r\n\r\n\t\t        $(this).find('.js-x-close').trigger('click');   \r\n\t\t    });\r\n\r\n\t\t    $(document).on('click', '#jumboIX__modal.active *', function(e){\r\n\t\t        e.stopPropagation();\r\n\r\n\t\t    });\r\n\r\n\t\t})\r\n\t<\/script>\r\n\r\n\t<div id=\"jumboIX__modal\" class=\"popup-jumboIX-modal-s1 wrap-jumboix wrap-jumboix__2 v-modal\">\r\n\t\t<div class=\"modal__inner\">\r\n\t\t\t<button class=\"x-close js-x-close\">x<\/button>\r\n\r\n\t\t\t<h2 class=\"jumbolix-heading \">\r\n\t\t\t\t&#35831;&#27714;&#36828;&#31243;&#21150;&#20844;&#23460;&#25253;&#20215;\t\t\t<\/h2>\r\n\r\n\t\t\t\r\n\t\t\t<form method=\"post\" class=\"js-form-ajax-request_form css-form-mod-v2 js_form_get_token\">\r\n\t\t\t\t   \r\n   \r\n   \r\n\r\n    <div class=\"cf-turnstile\" data-sitekey=\"0x4AAAAAAEH6U9G0luTp-GH1\">\r\n    <\/div>\r\n\r\n        \r\n\r\n   <input type=\"hidden\" name=\"_wp_http_referer\" value=\"https:\/\/iptp.org\/zh_CN\/wp-json\/wp\/v2\/pages\/18467\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"_current_title\" value=\"IPTP Networks\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"security\" value=\"ffd0b908b1\">\r\n   <input type=\"hidden\" name=\"form_time\" value=\"1788331451\">\r\n   <input type=\"text\" name=\"website\" class=\"no-check p-display-hide\">\r\n   <input type=\"hidden\" name=\"js_check\" class=\"no-check\" value=\"\">\r\n   \r\n\r\n\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"service\" value=\"&#36828;&#31243;&#21150;&#20844;&#23460;\">\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"your_name\" class=\"form-control form-control--border-bottom\" placeholder=\"Your name *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"email\" class=\"form-control form-control--border-bottom\" placeholder=\"E-mail *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"organisation\" class=\"form-control form-control--border-bottom\" placeholder=\"Organisation *\">\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<div class=\"wrap-intl-tel-input\">\r\n\t\t\t\t\t\t\t<input type=\"text\" name=\"asnumber\" class=\"form-control form-control--border-bottom intl-tel-input no-check\" placeholder=\"Phone Number\">\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t<div class=\"w-100\">\r\n\t\t\t\t\t\t\t<label class=\"p-bold\">Describe your request<\/label>\r\n\t\t\t\t\t\t\t<textarea name=\"message\" cols=\"30\" rows=\"6\" class=\"form-control form-control--border-bottom\" placeholder=\"Quick overview *\"><\/textarea>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t* &#24517;&#22635;&#23383;&#27573;\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 text-center\">\r\n\t\t\t\t\t<!-- \t<div class=\"line-group captcha_md\">\r\n\t\t\t\t\t\t\t<div id=\"captchas\" class=\"captcha__label\" data-qid=\"captcha_6a97c5bb9c473\"><\/div>\r\n\t\t\t\t\t\t\t<span class=\"fa fa-refresh catpcha_refreshs catpcha_refresh_mod\"><\/span>\r\n\t\t\t\t\t\t\t<input id=\"cpatchaJumboIX\" type=\"text\" name=\"captcha\" class=\"line-group__input--213 captcha__input--custom\" placeholder=\"Captcha code\" \/>\r\n\t\t\t\t\t\t<\/div> -->\r\n\t\t\t\t\t\t<div class=\"line-groups\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"hidden-sm hidden-xs\"><\/div>\r\n\t\t\t\t\t\t\t<button class=\"btn btn__jumboix\">\r\n\t\t\t\t\t\t\t\t&#35831;&#27714;&#25253;&#20215;\t\t\t\t\t\t\t<\/button>\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed js-jumboIX_completed--success \">\r\n\t\t\t\t\t\t\t&#24863;&#35874;&#24744;&#30340;&#35831;&#27714;\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed jumboIX_completed--error\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/form>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"div-overlay\"><\/div>\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":18459,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-inner-page.php","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/iptp.org\/zh_CN\/wp-json\/wp\/v2\/pages\/18467"}],"collection":[{"href":"https:\/\/iptp.org\/zh_CN\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iptp.org\/zh_CN\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iptp.org\/zh_CN\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iptp.org\/zh_CN\/wp-json\/wp\/v2\/comments?post=18467"}],"version-history":[{"count":139,"href":"https:\/\/iptp.org\/zh_CN\/wp-json\/wp\/v2\/pages\/18467\/revisions"}],"predecessor-version":[{"id":41736,"href":"https:\/\/iptp.org\/zh_CN\/wp-json\/wp\/v2\/pages\/18467\/revisions\/41736"}],"up":[{"embeddable":true,"href":"https:\/\/iptp.org\/zh_CN\/wp-json\/wp\/v2\/pages\/18459"}],"wp:attachment":[{"href":"https:\/\/iptp.org\/zh_CN\/wp-json\/wp\/v2\/media?parent=18467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}