{"id":47,"date":"2019-07-11T14:32:06","date_gmt":"2019-07-11T11:32:06","guid":{"rendered":"https:\/\/dev.iptp.com\/?p=47"},"modified":"2026-01-12T13:01:16","modified_gmt":"2026-01-12T10:01:16","slug":"dmms","status":"publish","type":"post","link":"https:\/\/iptp.org\/pt_PT\/dmms\/","title":{"rendered":"Servi\u00e7o Gerenciado de Mitiga\u00e7\u00e3o Distribu\u00edda contra DDoS"},"content":{"rendered":"<h6>O ataque DDoS (Distributed Denial of Service) &eacute; uma das amea&ccedil;as mais cr&iacute;ticas para qualquer organiza&ccedil;&atilde;o que realiza neg&oacute;cios online.<\/h6><p>Os ataques cibern&eacute;ticos est&atilde;o se tornando cada vez mais problem&aacute;ticos para as organiza&ccedil;&otilde;es que realizam neg&oacute;cios on-line. Atualmente, os problemas cr&iacute;ticos s&atilde;o os ataques de nega&ccedil;&atilde;o de servi&ccedil;o distribu&iacute;do (Distributed Denial of Service &ndash; DDoS). O DDoS &eacute; um tipo distribu&iacute;do de ataque que permite que o tr&aacute;fego de gera&ccedil;&atilde;o maliciosa congestione linhas de acesso &agrave; Internet, levando &agrave; nega&ccedil;&atilde;o de servi&ccedil;o e, como resultado, prejudicando a reputa&ccedil;&atilde;o de uma organiza&ccedil;&atilde;o e potencialmente levando a perda de receita, perda de clientes valiosos e perda de reputa&ccedil;&atilde;o no mercado . Todos os dias, esses ataques tornam-se mais sofisticados, tornando seus dados corporativos vulner&aacute;veis e as exig&ecirc;ncias de seguran&ccedil;a cada vez mais desafiadoras.<\/p><h4>Sobre o IPTP DMMS contra o DDoS<\/h4><p>Nas IPTP&nbsp; Networks, desenvolvemos uma maneira exclusiva de proteger sua empresa e sua base de clientes, projetada especificamente para fornecer prote&ccedil;&atilde;o inigual&aacute;vel contra DDoS e garantir a opera&ccedil;&atilde;o cont&iacute;nua de sua rede. Uma infra-estrutura de rede de alto desempenho de propriedade do IPTP permite o manuseio de imensas quantidades de tr&aacute;fego e filtragem r&aacute;pida de ataques, fornecendo uma recusa poderosa e a subsequente mitiga&ccedil;&atilde;o de uma amea&ccedil;a em potencial. Como resultado, deixamos sua rede com tr&aacute;fego estritamente leg&iacute;timo e voc&ecirc; &ndash; com controle total sobre seus neg&oacute;cios.<\/p><p><a href=\"\/wp-content\/uploads\/DMMSscheme.png\"><img decoding=\"async\" loading=\"lazy\" class=\"lazy aligncenter size-full wp-image-1463\" src=\"data:image\/gif;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" data-src=\"\/wp-content\/uploads\/DMMSscheme.png\" alt=\"\" width=\"1146\" height=\"595\" srcset=\"https:\/\/iptp.org\/wp-content\/uploads\/DMMSscheme.png 1146w, https:\/\/iptp.org\/wp-content\/uploads\/DMMSscheme-300x156.png 300w, https:\/\/iptp.org\/wp-content\/uploads\/DMMSscheme-768x399.png 768w, https:\/\/iptp.org\/wp-content\/uploads\/DMMSscheme-1024x532.png 1024w\" sizes=\"(max-width: 1146px) 100vw, 1146px\"><noscript><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-1463 lazy\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" alt=\"\" width=\"1146\" height=\"595\" srcset=\"https:\/\/iptp.org\/wp-content\/uploads\/DMMSscheme.png 1146w, https:\/\/iptp.org\/wp-content\/uploads\/DMMSscheme-300x156.png 300w, https:\/\/iptp.org\/wp-content\/uploads\/DMMSscheme-768x399.png 768w, https:\/\/iptp.org\/wp-content\/uploads\/DMMSscheme-1024x532.png 1024w\" sizes=\"(max-width: 1146px) 100vw, 1146px\" data-src=\"\/wp-content\/uploads\/DMMSscheme.png\"><\/noscript><\/a><\/p><p>O Servi&ccedil;o Gerenciado de Mitiga&ccedil;&atilde;o Distribu&iacute;da (DMMS) &eacute; a tecnologia de mitiga&ccedil;&atilde;o de ataques DDoS usando um per&iacute;metro de rede equipado com uma cadeia de poderosos firewalls de ajuste fino. Nossa solu&ccedil;&atilde;o tem quatro vantagens principais sobre a t&eacute;cnica cl&aacute;ssica de mitiga&ccedil;&atilde;o de DDoS chamada &ldquo;Clean Pipe&rdquo; ou &ldquo;Cleaning Center&rdquo; (centro de limpeza). <strong>A primeira &eacute; a lat&ecirc;ncia<\/strong> &ndash; o tr&aacute;fego &eacute; mitigado diretamente no per&iacute;metro da rede, evitando a necessidade de redirecionar o tr&aacute;fego para o &ldquo;Centro de limpeza&rdquo;. O pr&oacute;ximo aspecto &eacute; o <strong>tempo de rea&ccedil;&atilde;o<\/strong> &ndash; os firewalls otimizados detectam automaticamente a maioria dos tipos de inunda&ccedil;&atilde;o e iniciam imediatamente o processo de mitiga&ccedil;&atilde;o, tornando o tempo de rea&ccedil;&atilde;o pr&oacute;ximo de zero. Outra vantagem do servi&ccedil;o IPTP DMMS &eacute; uma <strong>enorme capacidade de rede<\/strong> de mais de 30 Tb \/ s, que permite resistir a ataques DDoS de banda larga sem o risco de degrada&ccedil;&atilde;o do servi&ccedil;o. E por &uacute;ltimo, mas n&atilde;o menos importante, s&atilde;o <strong>despesas. <\/strong>A atenua&ccedil;&atilde;o com a cl&aacute;ssica abordagem &ldquo;Centro de Limpeza \/ Tubula&ccedil;&atilde;o Limpa&rdquo; resulta na concentra&ccedil;&atilde;o de alto volume de tr&aacute;fego em um &uacute;nico ponto, o que geralmente requer a compra de largura de banda extra. O uso de uma rede distribu&iacute;da mundial de firewalls IPMS DMMS ajuda os clientes a evitar essas despesas inesperadas distribuindo o tr&aacute;fego entre v&aacute;rios pontos em nossa rede e eliminando a alta carga combinada em um &uacute;nico n&oacute;.<\/p><p><strong>A efic&aacute;cia do Servi&ccedil;o Gerenciado de Mitiga&ccedil;&atilde;o Distribu&iacute;da em rela&ccedil;&atilde;o ao DDoS projetado e implementado pelas Redes IPTP &eacute; explicada por uma s&eacute;rie de vantagens:<\/strong><\/p><h5>Sem lat&ecirc;ncia adicionada.<\/h5><p>O tr&aacute;fego &eacute; mitigado diretamente no per&iacute;metro da rede evitando a necessidade de redirecionar o tr&aacute;fego para o &ldquo;Centro de Limpeza&rdquo;.<\/p><h5>Sem tempo de rea&ccedil;&atilde;o.<\/h5><p>Os Firewalls ajustados detectam automaticamente a maioria dos tipos de inunda&ccedil;&otilde;es e iniciam imediatamente o processo de mitiga&ccedil;&atilde;o, tornando o tempo de rea&ccedil;&atilde;o pr&oacute;ximo de zero.<\/p><h5>Limites de largura de banda mais altos em uma ordem de magnitude.<\/h5><p>Ao contr&aacute;rio de outras empresas que oferecem prote&ccedil;&atilde;o contra DDoS atrav&eacute;s de centros de limpeza limitados, operamos nossa pr&oacute;pria rede global de limpeza. Portanto, o tr&aacute;fego malicioso nunca foi agregado e limpo imediatamente ao longo de todo o per&iacute;metro de nossa rede. 1500 de portas de 10 Gbps distribu&iacute;das em todo o mundo e a capacidade total de rede de mais de 30 Tb \/ s nos permite suportar ataques pesados de largura de banda. IPTP DMMS Network &eacute; uma solu&ccedil;&atilde;o definitiva para proteger seus recursos contra a maioria dos tipos de ataques DDoS volum&eacute;tricos.<\/p><h5>Sem custos adicionais para sobrecarga de largura de banda.<\/h5><p>O tr&aacute;fego &eacute; distribu&iacute;do entre v&aacute;rios pontos, de modo que nenhum volume combinado de tr&aacute;fego atinge um &uacute;nico n&oacute; da rede. Uma grande vantagem da nossa solu&ccedil;&atilde;o &eacute; que o tr&aacute;fego mal-intencionado &eacute; limpo antes de chegar &agrave; nossa rede, portanto, nenhum custo adicional ser&aacute; aplicado &agrave; largura de banda extra.<\/p><h5>Solu&ccedil;&atilde;o tecnicamente avan&ccedil;ada contra DDoS<\/h5><p>Firewalls&nbsp;DMMS altamente personalizados da IPTP NETWORKS podem lidar com qualquer tipo de protocolo, a partir de HTTP padr&atilde;o para qualquer TCP e at&eacute; mesmo protocolos UDP baseados em criptografia usados em setores financeiros, garantindo que cada solicita&ccedil;&atilde;o seja atendida.<br>\nOs firewalls avan&ccedil;ados da rede IPTP DMMS podem lidar com v&aacute;rios gigabits de tr&aacute;fego e filtrar todos os tipos de inunda&ccedil;&otilde;es de tr&aacute;fego, incluindo, entre outros, ICMP, UDP e SYN. Nossos especialistas qualificados lidam diariamente com cargas elevadas de tr&aacute;fego e operam em equipamentos de rede de ponta da Cisco, um provedor l&iacute;der do setor, para garantir que sua empresa receba o desempenho sustent&aacute;vel inigual&aacute;vel e a prote&ccedil;&atilde;o cont&iacute;nua de que necessita.<\/p><div>\r\n\t\t<button type=\"button\" class=\"btn btn-primary btn__jumboix btn-lg js-target-div mt-2 js-fixed-button-open-request-form \" data-target=\"jumboIX__modal\">\r\n\t\t\tRequest a quote\t\t<\/button>\r\n\t<\/div><script type=\"text\/javascript\">\r\n\t\tjQuery(function($){\r\n\r\n\t\t\t $(document).on('click', '#jumboIX__modal.active', function(e){\r\n\t\t        e.preventDefault();\r\n\r\n\t\t        $(this).find('.js-x-close').trigger('click');   \r\n\t\t    });\r\n\r\n\t\t    $(document).on('click', '#jumboIX__modal.active *', function(e){\r\n\t\t        e.stopPropagation();\r\n\r\n\t\t    });\r\n\r\n\t\t})\r\n\t<\/script><div id=\"jumboIX__modal\" class=\"popup-jumboIX-modal-s1 wrap-jumboix wrap-jumboix__2 v-modal\">\r\n\t\t<div class=\"modal__inner\">\r\n\t\t\t<button class=\"x-close js-x-close\">x<\/button>\r\n\r\n\t\t\t<h2 class=\"jumbolix-heading \">\r\n\t\t\t\tRequest a quote for DDoS mitigation service\t\t\t<\/h2>\r\n\r\n\t\t\t\r\n\t\t\t<form method=\"post\" class=\"js-form-ajax-request_form css-form-mod-v2 js_form_get_token\">\r\n\t\t\t\t   \r\n   \r\n   \r\n\r\n    <div class=\"cf-turnstile\" data-sitekey=\"0x4AAAAAAEH6U9G0luTp-GH1\">\r\n    <\/div>\r\n\r\n        \r\n\r\n   <input type=\"hidden\" name=\"_wp_http_referer\" value=\"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/posts\/47\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"_current_title\" value=\"IPTP Networks\" class=\"no-check\">\r\n   <input type=\"hidden\" name=\"security\" value=\"ffd0b908b1\">\r\n   <input type=\"hidden\" name=\"form_time\" value=\"1788336439\">\r\n   <input type=\"text\" name=\"website\" class=\"no-check p-display-hide\">\r\n   <input type=\"hidden\" name=\"js_check\" class=\"no-check\" value=\"\">\r\n   \r\n\r\n\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"service\" value=\"DDoS mitigation service\">\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"your_name\" class=\"form-control form-control--border-bottom\" placeholder=\"Your name *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"email\" class=\"form-control form-control--border-bottom\" placeholder=\"E-mail *\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<input type=\"text\" name=\"organisation\" class=\"form-control form-control--border-bottom\" placeholder=\"Organisation *\">\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-6 line-group\">\r\n\t\t\t\t\t\t<div class=\"wrap-intl-tel-input\">\r\n\t\t\t\t\t\t\t<input type=\"text\" name=\"asnumber\" class=\"form-control form-control--border-bottom intl-tel-input no-check\" placeholder=\"Phone Number\">\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t<div class=\"w-100\">\r\n\t\t\t\t\t\t\t<label class=\"p-bold\">Describe your request<\/label>\r\n\t\t\t\t\t\t\t<textarea name=\"message\" cols=\"30\" rows=\"6\" class=\"form-control form-control--border-bottom\" placeholder=\"Quick overview *\"><\/textarea>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 line-group\">\r\n\t\t\t\t\t\t* required fields\t\t\t\t\t<\/div>\r\n\r\n\r\n\t\t\t\t\t<div class=\"col-xs-12 col-md-12 text-center\">\r\n\t\t\t\t\t<!-- \t<div class=\"line-group captcha_md\">\r\n\t\t\t\t\t\t\t<div id=\"captchas\" class=\"captcha__label\" data-qid=\"captcha_6a97d93714646\"><\/div>\r\n\t\t\t\t\t\t\t<span class=\"fa fa-refresh catpcha_refreshs catpcha_refresh_mod\"><\/span>\r\n\t\t\t\t\t\t\t<input id=\"cpatchaJumboIX\" type=\"text\" name=\"captcha\" class=\"line-group__input--213 captcha__input--custom\" placeholder=\"Captcha code\" \/>\r\n\t\t\t\t\t\t<\/div> -->\r\n\t\t\t\t\t\t<div class=\"line-groups\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"hidden-sm hidden-xs\"><\/div>\r\n\t\t\t\t\t\t\t<button class=\"btn btn__jumboix\">\r\n\t\t\t\t\t\t\t\tRequest a quote\t\t\t\t\t\t\t<\/button>\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed js-jumboIX_completed--success \">\r\n\t\t\t\t\t\t\tThank you for your request\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div class=\"jumboIX_completed jumboIX_completed--error\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/form>\r\n\t\t<\/div>\r\n\t<\/div><div class=\"div-overlay\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Projetada especificamente para fornecer prote\u00e7\u00e3o inigual\u00e1vel contra DDoS e garantir a opera\u00e7\u00e3o cont\u00ednua de sua rede.<\/p>\n","protected":false},"author":1,"featured_media":12953,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":[],"categories":[1],"tags":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/posts\/47"}],"collection":[{"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":188,"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/posts\/47\/revisions"}],"predecessor-version":[{"id":38788,"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/posts\/47\/revisions\/38788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/media\/12953"}],"wp:attachment":[{"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/media?parent=47"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/categories?post=47"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iptp.org\/pt_PT\/wp-json\/wp\/v2\/tags?post=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}